{"id":13798,"date":"2026-07-07T07:39:05","date_gmt":"2026-07-07T07:39:05","guid":{"rendered":"https:\/\/caixamagica.pt\/?post_type=new&#038;p=13798"},"modified":"2026-07-14T09:38:56","modified_gmt":"2026-07-14T09:38:56","slug":"welche-anderungen-bringt-ki-gestutztes-testen-mit-sich","status":"publish","type":"new","link":"https:\/\/caixamagica.pt\/de\/insights\/welche-anderungen-bringt-ki-gestutztes-testen-mit-sich\/","title":{"rendered":"Was sich wirklich \u00e4ndert, wenn Ihr Team mit KI-unterst\u00fctzten Tests beginnt"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13798\" class=\"elementor elementor-13798\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e02408f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e02408f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b109e63\" data-id=\"b109e63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a368bc8 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"a368bc8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n.cms-stat-grid {\n  display: grid;\n  grid-template-columns: repeat(3, 1fr);\n  gap: 1px;\n  background: #e5e5e5;\n  border: 1px solid #e5e5e5;\n  border-radius: 12px;\n  overflow: hidden;\n  margin: 2rem 0;\n}\n@media (max-width: 520px) {\n  .cms-stat-grid { grid-template-columns: 1fr; }\n}\n.cms-stat-cell {\n  background: #ffffff;\n  padding: 1.75rem 1.25rem;\n  text-align: center;\n}\n.cms-stat-num {\n  display: block;\n  font-size: 2rem;\n  font-weight: 800;\n  letter-spacing: -0.04em;\n  line-height: 1;\n  color: #111111;\n  margin-bottom: 0.5rem;\n}\n.cms-stat-num.blue { color: #2563eb; }\n.cms-stat-num.sm { font-size: 1.375rem; letter-spacing: -0.025em; }\n.cms-stat-lbl {\n  font-size: 0.8125rem;\n  color: #888888;\n  line-height: 1.5;\n}\n<\/style>\n\n<style>\n.cms-pullquote {\n  border-left: 3px solid #2563eb;\n  padding: 0.5rem 0 0.5rem 1.5rem;\n  line-height: 1.55;\n  letter-spacing: -0.015em;\n  margin: 2rem 0;\n}\n<\/style>\n\n<style>\n.cms-cmp-wrap {\n  border: 1px solid #e5e5e5;\n  border-radius: 12px;\n  overflow: hidden;\n  margin: 2rem 0;\n}\n.cms-cmp-table {\n  width: 100%;\n  border-collapse: collapse;\n  font-size: 0.9375rem;\n}\n.cms-cmp-table thead tr {\n  background: #f7f7f7;\n  border-bottom: 1px solid #e5e5e5;\n}\n.cms-cmp-table th {\n  padding: 0.875rem 1.125rem;\n  text-align: left;\n  font-size: 0.6875rem;\n  font-weight: 700;\n  letter-spacing: 0.07em;\n  text-transform: uppercase;\n  color: #888888;\n}\n.cms-cmp-table th:nth-child(2) { text-align: center; }\n.cms-cmp-table th:nth-child(3) {\n  text-align: center;\n  color: #2563eb;\n  background: #eff6ff;\n}\n.cms-cmp-table td {\n  padding: 0.875rem 1.125rem;\n  border-bottom: 1px solid #e5e5e5;\n  color: #333333;\n  vertical-align: middle;\n}\n.cms-cmp-table tr:last-child td { border-bottom: none; }\n.cms-cmp-table td:nth-child(1) {\n  font-weight: 500;\n  color: #111111;\n}\n.cms-cmp-table td:nth-child(2) {\n  text-align: center;\n  color: #888888;\n  font-size: 0.875rem;\n}\n.cms-cmp-table td:nth-child(3) {\n  text-align: center;\n  background: #eff6ff;\n  color: #2563eb;\n  font-weight: 700;\n  font-size: 0.875rem;\n}\n.cms-cmp-note {\n  padding: 0.875rem 1.125rem;\n  background: #f7f7f7;\n  border-top: 1px solid #e5e5e5;\n  font-size: 0.8125rem;\n  color: #888888;\n}\n<\/style>\n\n<style>\n.cms-feat-list {\n  border: 1px solid #e5e5e5;\n  border-radius: 12px;\n  overflow: hidden;\n  margin: 2rem 0;\n}\n.cms-feat-card {\n  display: grid;\n  grid-template-columns: 2.25rem 1fr;\n  gap: 1rem;\n  align-items: start;\n  padding: 1.375rem 1.5rem;\n  background: #ffffff;\n  border-bottom: 1px solid #e5e5e5;\n}\n.cms-feat-card:last-child { border-bottom: none; }\n.cms-feat-icon {\n  width: 2.125rem;\n  height: 2.125rem;\n  border-radius: 7px;\n  background: #eff6ff;\n  flex-shrink: 0;\n  margin-top: 0.1rem;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n.cms-feat-icon svg {\n  width: 15px;\n  height: 15px;\n  stroke: #2563eb;\n  fill: none;\n  stroke-width: 2;\n  stroke-linecap: round;\n  stroke-linejoin: round;\n}\n.cms-feat-title {\n  font-size: 0.9375rem;\n  font-weight: 700;\n  color: #111111;\n  margin-bottom: 0.35rem;\n}\n.cms-feat-body {\n  font-size: 0.9375rem;\n  color: #333333;\n  line-height: 1.65;\n}\n<\/style>\n\n<style>\n.cms-cta-wrap {\n  background: #2563eb;\n  border-radius: 12px;\n  padding: 4rem 2rem;\n  text-align: center;\n  margin: 2rem 0;\n}\n.cms-cta-eyebrow {\n  font-size: 0.6875rem;\n  font-weight: 700;\n  letter-spacing: 0.1em;\n  text-transform: uppercase;\n  color: rgba(255,255,255,0.75);\n  margin-bottom: 1rem;\n}\n.cms-cta-title {\n  font-size: clamp(1.5rem, 3vw, 2rem);\n  font-weight: 800;\n  color: #ffffff;\n  letter-spacing: -0.03em;\n  line-height: 1.2;\n  margin-bottom: 1rem;\n  max-width: 600px;\n  margin-left: auto;\n  margin-right: auto;\n}\n.cms-cta-sub {\n  font-size: 1rem;\n  color: rgba(255,255,255,0.8);\n  line-height: 1.65;\n  margin-bottom: 2rem;\n}\n.cms-cta-btns {\n  display: flex;\n  gap: 0.75rem;\n  justify-content: center;\n  flex-wrap: wrap;\n}\n.cms-btn-primary {\n  font-size: 0.9375rem;\n  font-weight: 600;\n  color: #111111;\n  background: #ffffff;\n  padding: 0.8125rem 1.625rem;\n  border-radius: 8px;\n  text-decoration: none;\n  letter-spacing: -0.01em;\n  display: inline-block;\n}\n.cms-btn-primary:hover { background: #f0f0f0; }\n.cms-btn-secondary {\n  font-size: 0.9375rem;\n  font-weight: 600;\n  color: rgba(255,255,255,0.9);\n  background: transparent;\n  border: 1px solid rgba(255,255,255,0.2);\n  padding: 0.8125rem 1.625rem;\n  border-radius: 8px;\n  text-decoration: none;\n  letter-spacing: -0.01em;\n  display: inline-block;\n}\n.cms-btn-secondary:hover {\n  border-color: rgba(255,255,255,0.45);\n  color: #ffffff;\n}\n<\/style>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64972e4 elementor-widget elementor-widget-html\" data-id=\"64972e4\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p>Die Unterhaltung \u00fcber KI-gest\u00fctzte Tests konzentriert sich tendenziell auf das Werkzeug: was es generiert, wie schnell, mit welcher Abdeckung. Die wichtigere Unterhaltung \u2013 und die, die am ehrlichsten zu f\u00fchren ist \u2013 dreht sich jedoch darum, was sich f\u00fcr das Team \u00e4ndert, das es nutzt.<\/p>\n\n<p>Es gibt eine Version dieser Konversation, die bei den Zahlen aufh\u00f6rt: mehr generierte Testf\u00e4lle, h\u00f6here Abdeckung, schnell.<\/p>\n\n  <p>Der Aufbau von Qualigentic hat uns gezwungen, pr\u00e4zise zu definieren, was sich tats\u00e4chlich verschiebt, wenn KI in den Testablauf integriert wird \u2014 nicht was automatisiert wird, sondern was neu \u00fcberdacht wird. Das ist es, was wir hier teilen.<\/p>\n\n  <div class=\"cms-stat-grid\">\n    <div class=\"cms-stat-cell\">\n      <span class=\"cms-stat-num blue\">60\u201370%<\/span>\n      <span class=\"cms-stat-lbl\">der QA-Aufwand f\u00fcr die Wartung bestehender Tests \u2013 nicht f\u00fcr das Schreiben neuer Tests<\/span>\n    <\/div>\n    <div class=\"cms-stat-cell\">\n      <span class=\"cms-stat-num sm\">Erzeugung \u2192 Instandhaltung<\/span>\n      <span class=\"cms-stat-lbl\">Der gr\u00f6\u00dfere Gewinn sind nicht die Tests, die die KI zuerst schreibt \u2013 es sind die, die sie danach am Leben erh\u00e4lt<\/span>\n    <\/div>\n    <div class=\"cms-stat-cell\">\n      <span class=\"cms-stat-num sm\">Aufmerksamkeit, nicht Anstrengung<\/span>\n      <span class=\"cms-stat-lbl\">Was sich \u00e4ndert, ist, wo das technische Urteilsverm\u00f6gen einflie\u00dft \u2013 nicht, ob es noch gebraucht wird<\/span>\n    <\/div>\n  <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43bed59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43bed59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a22d1d\" data-id=\"3a22d1d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a61ab9f elementor-widget elementor-widget-html\" data-id=\"a61ab9f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t <h2>Das Erste, was sich \u00e4ndert, ist, worauf die Aufmerksamkeit der Ingenieure gerichtet ist<\/h2>\n\n<p>In einem herk\u00f6mmlichen Test-Workflow flie\u00dft der Gro\u00dfteil der kognitiven Anstrengung eines Ingenieurs in eine bestimmte Art von Arbeit. Das bedeutet, Anforderungen in Testf\u00e4lle zu \u00fcbersetzen, die wichtigen Szenarien zu identifizieren, die Logik zu schreiben, die sie \u00fcberpr\u00fcft, und diese Logik zu pflegen, w\u00e4hrend sich der Code darunter weiterentwickelt. Dies ist qualifizierte Arbeit und erfordert ein echtes Verst\u00e4ndnis des zu testenden Systems. Ein erheblicher Teil davon ist jedoch auch formelhaft \u2013 die Grenzbedingungen, die Szenarien zur Eingabevalidierung und die Standardfehlerpfade, die in jeder Codebasis existieren und abgedeckt werden m\u00fcssen, unabh\u00e4ngig davon, wie interessant sie sind.<\/p>\n\n<p>Wenn KI die Generierung dieser Art von Tests \u00fcbernimmt, geschieht etwas, das sorgf\u00e4ltig beachtet werden muss: Sie reduziert nicht die Beteiligung des Ingenieurs an der Qualit\u00e4t. Stattdessen verschiebt sich die Stelle, an die sich diese Beteiligung richtet.<\/p>\n\n<p>Die Arbeit, die KI gut macht, ist die systematische, ersch\u00f6pfende Art. Zum Beispiel stellt sie sicher, dass bekannte Fehlerkategorien abgedeckt sind, dass Grenzf\u00e4lle nicht versehentlich \u00fcbersehen werden und dass die Abdeckung konsistent ist und nicht davon abh\u00e4ngt, was dem Ingenieur an einem bestimmten Tag eingefallen ist. Im Gegensatz dazu ist die Arbeit, die immer noch menschliches Urteilsverm\u00f6gen erfordert, die interessantere Art: zu entscheiden, was in diesem.<\/p>\n\n<p>Diese Umverteilung der Aufmerksamkeit ist kein nebens\u00e4chliches Detail. Teams, die sie erfahren, beschreiben sie oft als eine Verlagerung vom Schreiben von Tests hin zum Nachdenken dar\u00fcber, was getestet werden sollte. Kurz gesagt, es ist eine wertvollere Nutzung der Zeit eines Ingenieurs, mit Konsequenzen, die sich \u00fcber die Lebensdauer einer Codebasis hinweg verst\u00e4rken, anstatt eines einmaligen Gewinns, der im ersten Sprint aufgebraucht ist.<\/p>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bfb948 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bfb948\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f640fd\" data-id=\"6f640fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56a2fbf elementor-widget elementor-widget-html\" data-id=\"56a2fbf\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2>Die zweite Sache, die sich \u00e4ndert, ist die Unterhaltung \u00fcber die Abdeckung.<\/h2>\n\n<p>Die Abdeckungsquote ist eine der am engsten verfolgten Kennzahlen in der Softwarequalit\u00e4t. Sie ist auch eine der am meisten missverstandenen, denn eine hohe <a href=\"https:\/\/glossary.istqb.org\/en_US\/term\/coverage\" target=\"_blank\" rel=\"noopener\">Testabdeckung<\/a> ist nicht gleichbedeutend mit einer guten Testabdeckung. Tats\u00e4chlich kann eine Testsuite, die 90% der Codebasis abdeckt, dennoch den spezifischen Fehlerfall \u00fcbersehen, der einen Produktionsausfall verursacht, wenn die Tests darauf ausgelegt sind, Codezeilen abzudecken, anstatt das Verhalten zu \u00fcberpr\u00fcfen.<\/p>\n\n<p>Vor KI-gest\u00fctzten Tests war die Diskussion \u00fcber die Abdeckung in den meisten Teams im Grunde eine Diskussion \u00fcber den Aufwand. Genauer gesagt: Wie viel Zeit wird ben\u00f6tigt, um gen\u00fcgend Tests zu schreiben, um den Zielprozentsatz zu erreichen, und steht diese Zeit angesichts der Anforderungen des Sprints zur Verf\u00fcgung? In der Praxis war dies eine Ressourcenverhandlung, die als Qualit\u00e4tsdiskussion getarnt war.<\/p>\n\n<p>Nach KI-gest\u00fctzten Tests \u00e4ndert sich die Art der Konversation. Die Frage, ob es gen\u00fcgend Tests gibt, l\u00e4sst sich leichter beantworten, da die Generierung von Tests in gro\u00dfem Ma\u00dfstab nicht mehr der Engpass ist. Stattdessen r\u00fcckt die Frage, die sich zum Zentrum bewegt, eine schwierigere Frage in den Mittelpunkt: Pr\u00fcfen diese Tests die richtigen Dinge? Ist die Abdeckung aussagekr\u00e4ftig oder mechanisch? Gibt die Testsuite echtes Vertrauen, dass das System korrekt funktioniert, oder erweckt sie nur den Anschein von Vertrauen, ohne Substanz dahinter?<\/p>\n\n<p>Es ist ein schwierigeres Gespr\u00e4ch, und es erfordert, dass die Ingenieurteams pr\u00e4ziser darin werden, was sie tats\u00e4chlich verifizieren wollen und warum. Dennoch ist es das richtige Gespr\u00e4ch \u2013 das einzige, das die Testpraxis wirklich mit der Zuverl\u00e4ssigkeit dessen verbindet, was ausgeliefert wird.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-812e8b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"812e8b6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0033842\" data-id=\"0033842\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f36a5d1 elementor-widget elementor-widget-html\" data-id=\"f36a5d1\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2>Der dritte Punkt, der sich \u00e4ndert, ist, wenn Qualit\u00e4t in den Entwicklungszyklus einflie\u00dft<\/h2>\n\n <p>Eines der strukturellen Probleme bei der Qualit\u00e4t in den meisten Softwareteams ist der Zeitpunkt. Testen wird fast immer als nachgelagerte Aktivit\u00e4t behandelt \u2013 etwas, das nach dem Schreiben des Codes stattfindet, um zu \u00fcberpr\u00fcfen, ob das, was erstellt wurde, korrekt ist. Dies ist teilweise kulturell und teilweise wirtschaftlich bedingt. Insbesondere erfordert das Testen etwas zum Testen, und der praktische Druck der Entwicklung tendiert dazu, es gegen Ende des Sprints zu verschieben.<\/p>\n\n<p>Die Konsequenz ist vorhersehbar: Sp\u00e4t entdeckte Fehler sind teuer zu beheben. Bis dahin ist der zu \u00e4ndernde Code bereits mit anderem Code integriert und der Ingenieur, der ihn geschrieben hat, hat sich etwas anderem zugewandt. Jeder Kontext, der zur ordnungsgem\u00e4\u00dfen Behebung ben\u00f6tigt wird, muss aus dem Ged\u00e4chtnis oder der Dokumentation rekonstruiert werden. Infolgedessen ist die Behebung selbst \u2013 unter Zeitdruck und am Ende eines Zyklus \u2013 mit h\u00f6herer Wahrscheinlichkeit fehleranf\u00e4lliger als eine fr\u00fchere Behebung, als das System noch entworfen wurde.<\/p>\n\n<p>KI-gest\u00fctzte Tests ver\u00e4ndern die \u00d6konomie dieses Timing-Problems. Wenn die Erstellung einer Testsuite nicht mehr denselben Aufwand an Ingenieurszeit erfordert, schw\u00e4cht sich die Begr\u00fcndung f\u00fcr deren Verschiebung ab. Folglich k\u00f6nnen Tests kontinuierlich w\u00e4hrend der gesamten Entwicklung erstellt und ausgef\u00fchrt werden, anstatt angesammelt und am Ende ausgel\u00f6st zu werden. Der Regelkreis wird k\u00fcrzer, sodass Fehler auftauchen, wenn ihre Behebung am g\u00fcnstigsten ist.<\/p>\n\n<p>Dies ist keine Behauptung, dass KI-gest\u00fctzte Tests das kulturelle Problem der sp\u00e4ten Qualit\u00e4tskontrolle l\u00f6sen \u2013 Kultur ver\u00e4ndert sich nicht, weil sich ein Werkzeug ge\u00e4ndert hat. Sie ver\u00e4ndert jedoch die Anreize. Und unterschiedliche Anreize, die \u00fcber einen l\u00e4ngeren Zeitraum bestehen bleiben, ver\u00e4ndern schlie\u00dflich die Kultur.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2627df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2627df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0897605\" data-id=\"0897605\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9221d7e elementor-widget elementor-widget-html\" data-id=\"9221d7e\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2>Die vierte Sache, die sich \u00e4ndert, ist der Wartungsaufwand<\/h2>\n\n  <p>Die wahren Kosten einer Testsuite sind nicht die Kosten f\u00fcr ihre Erstellung. Das ist der sichtbare Teil, f\u00fcr den man leicht Budget einplanen kann. Vielmehr sind die tats\u00e4chlichen Kosten, die sich \u00fcber Monate und Jahre ansammeln, der Aufwand, sie funktionsf\u00e4hig zu halten.<\/p>\n\n<p>Im Zuge der Weiterentwicklung einer Codebasis fallen Tests aus. Manche fallen aus, weil sie einen echten Fehler aufgedeckt haben, w\u00e4hrend viele andere einfach deshalb ausfallen, weil sich die Implementierung in einer Weise ge\u00e4ndert hat, die zwar das Verhalten nicht beeinflusst, aber die Testlogik betrifft. Diese beiden Kategorien \u2013 echte Fehler gegen\u00fcber veralteten Tests \u2013 voneinander zu unterscheiden, ist zeitaufw\u00e4ndig. Dazu muss man die urspr\u00fcngliche Absicht des Tests, den aktuellen Zustand des Codes und die Frage verstehen, ob dieser Test noch etwas Sinnvolles pr\u00fcft. Bemerkenswert ist, dass Branchenangaben den Anteil des QA-Aufwands f\u00fcr die Testpflege auf etwa 60% bis 70% beziffern. Mit anderen Worten: Der Gro\u00dfteil der Zeit einer QA-Abteilung flie\u00dft nicht in die Suche nach neuen Problemen, sondern in die Aufrechterhaltung der Testinfrastruktur. Dies deckt sich mit umfassenderen Erkenntnissen aus der Studie von Capgemini <a href=\"https:\/\/www.capgemini.com\/insights\/research-library\/world-quality-report-2025-26\/\" target=\"_blank\" rel=\"noopener\">World Quality Report<\/a>, das verfolgt, wie viel Qualit\u00e4tssicherungsaufwand branchenweit f\u00fcr die Wartung statt f\u00fcr die neue Abdeckung aufgewendet wird.<\/p>\n\n<p>Wenn KI einen Teil dieser Wartung \u00fcbernimmt, \u00e4ndert sich der Charakter von QA-Arbeit erheblich. Konkret bedeutet dies, Tests zu kennzeichnen, die veraltet.<\/p>\n\n<p>In der Praxis ist dies oft der bedeutsamere Gewinn, mehr noch als der anf\u00e4ngliche Vorteil der automatisierten Testgenerierung. Der Generierungsnutzen ist sofort sichtbar, w\u00e4hrend sich der Wartungsnutzen \u00fcber die Lebensdauer der Codebasis hinweg kumuliert \u2013 genau deshalb ist er bei einer schnellen Einsch\u00e4tzung leicht zu untersch\u00e4tzen.<\/p>\n\n  <h2>Der f\u00fcnfte Punkt, und der am leichtesten zu \u00fcbersehende: die Gefahr des falschen Selbstvertrauens<\/h2>\n\n <p>Es gibt eine spezifische Falle, die erst dann sichtbar wird, wenn ein Team beginnt, sich auf die automatische Testgenerierung zu verlassen: die M\u00f6glichkeit, ein Problem durch ein anderes zu ersetzen. Zuvor bestand die Gefahr, zu wenige Tests zu haben. Jetzt besteht die Gefahr jedoch darin, eine gro\u00dfe Anzahl von Tests zu haben, die solide erscheinen, aber tats\u00e4chlich die gleiche Unsicherheit widerspiegeln, die bereits in den Anforderungen bestand \u2013 nur in gr\u00f6\u00dferem Umfang und mit dem Anschein von Stringenz.<\/p>\n\n<p>Ein automatisch generierter Test ist nur so gut wie das Verst\u00e4ndnis des Modells f\u00fcr das erwartete Verhalten. Wenn dieses Verst\u00e4ndnis falsch ist oder die zugrundeliegende Anforderung mehrdeutig ist, ist das Ergebnis nicht die Abwesenheit von Tests. Stattdessen ist es eine Reihe von Tests, die konsistent bestanden werden, ein falsches Sicherheitsgef\u00fchl vermitteln und das Problem erst dann aufdecken, wenn das System auf eine Weise ausf\u00e4llt, die niemand erwartet hat. Dies ist ein stilles Risiko, gerade weil es in keinem Bericht auftaucht: die Tests existieren, sie laufen und sie bestehen.<\/p>\n\n<blockquote>Die Frage ist nie, wie viele Tests wir haben, sondern ob die Tests das Richtige pr\u00fcfen.<\/blockquote>\n\n<p>Dies ist auch der Grund, warum die menschliche \u00dcberpr\u00fcfung von generierten Tests \u2013 und nicht nur von Produktionscode \u2013 zu einer Disziplin mit eigenem Wert wird, anstatt ein Restschritt, der bei.<\/p>\n\n<h3>Die f\u00fcnf Schichten, nebeneinander<\/h3>\n\n  <div class=\"cms-cmp-wrap\">\n    <table class=\"cms-cmp-table\">\n      <thead>\n        <tr>\n          <th>Was \u00e4ndert sich<\/th>\n          <th>Vor KI-gest\u00fctzten Tests<\/th>\n          <th>Nach KI-gest\u00fctzten Tests<\/th>\n        <\/tr>\n      <\/thead>\n      <tbody>\n        <tr>\n          <td>Ingenieur-Aufmerksamkeit<\/td>\n          <td>Schreibe die Logik f\u00fcr Routine-Tests<\/td>\n          <td>\u2713 Entscheiden, was wirklich testenswert ist<\/td>\n        <\/tr>\n        <tr>\n          <td>Versicherungsgespr\u00e4ch<\/td>\n          <td>Haben wir genug Tests?<\/td>\n          <td>\u2713 Werden bei diesen Tests die richtigen Aspekte gepr\u00fcft?<\/td>\n        <\/tr>\n        <tr>\n          <td>Qualit\u00e4t des Timings<\/td>\n          <td>Verschoben bis zum Ende des Sprints<\/td>\n          <td>\u2713 Kontinuierlich generiert und ausgef\u00fchrt<\/td>\n        <\/tr>\n        <tr>\n          <td>Wartung<\/td>\n          <td>60\u201370%: QA-Zeiterfassungstests werden aufrechterhalten<\/td>\n          <td>\u2713 Veraltete Tests gekennzeichnet und \u00fcberarbeitet<\/td>\n        <\/tr>\n        <tr>\n          <td>Selbstvertrauen<\/td>\n          <td>Risiko zu geringer Tests, bekannte L\u00fccken<\/td>\n          <td>\u2713 Risiko verschiebt sich zu falscher Zuversicht \u2014 \u00dcberpr\u00fcfung erforderlich<\/td>\n        <\/tr>\n      <\/tbody>\n    <\/table>\n    <div class=\"cms-cmp-note\">Das Werkzeug \u00e4ndert, was automatisiert wird. Das Team \u00e4ndert, worauf es achtet.<\/div>\n  <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0aad73e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0aad73e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5e16d0\" data-id=\"c5e16d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed7edce elementor-widget elementor-widget-html\" data-id=\"ed7edce\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2>Was KI-gest\u00fctztes Testen nicht \u00e4ndert<\/h2>\n\n<p>Es lohnt sich, pr\u00e4zise zu sein, was KI-gest\u00fctztes Testen nicht ver\u00e4ndert. Behauptungen \u00fcber KI-Tools neigen dazu, ausschweifend zu sein, daher ist Pr\u00e4zision hier n\u00fctzlicher als Begeisterung.<\/p>\n\n  <div class=\"cms-feat-list\">\n    <div class=\"cms-feat-card\">\n      <div class=\"cms-feat-icon\">\n        <svg viewbox=\"0 0 24 24\"><path d=\"M12 20h9\"\/><path d=\"M16.5 3.5a2.121 2.121 0 013 3L7 19l-4 1 1-4L16.5 3.5z\"\/><\/svg>\n      <\/div>\n      <div>\n        <div class=\"cms-feat-title\">KI schafft nicht die Notwendigkeit ab, das zu testende System zu verstehen<\/div>\n        <div class=\"cms-feat-body\">Generierte Tests sind nur so gut wie das Verst\u00e4ndnis des Modells f\u00fcr den Code und das erwartete Verhalten. Randf\u00e4lle, die spezifisch f\u00fcr die tats\u00e4chliche Nutzung eines Produkts sind, erfordern immer noch menschliches Wissen zur Identifizierung und menschliches Urteilsverm\u00f6gen zur Priorisierung.<\/div>\n      <\/div>\n    <\/div>\n    <div class=\"cms-feat-card\">\n      <div class=\"cms-feat-icon\">\n        <svg viewbox=\"0 0 24 24\"><circle cx=\"12\" cy=\"12\" r=\"9\"\/><path d=\"M12 7v5l3 3\"\/><\/svg>\n      <\/div>\n      <div>\n        <div class=\"cms-feat-title\">Schlecht spezifizierte Anforderungen werden immer noch nicht von KI gel\u00f6st<\/div>\n        <div class=\"cms-feat-body\">Ein Test, der falsches Verhalten \u00fcberpr\u00fcft, ist schlechter als gar kein Test. Wenn die Anforderung unklar war, kann der generierte Test diese Unklarheit getreu wiedergeben \u2013 und best\u00e4ndig bestehen, bis das System auf eine unerwartete Weise ausf\u00e4llt.<\/div>\n      <\/div>\n    <\/div>\n    <div class=\"cms-feat-card\">\n      <div class=\"cms-feat-icon\">\n        <svg viewbox=\"0 0 24 24\"><path d=\"M17 21v-2a4 4 0 0 0-4-4H5a4 4 0 0 0-4 4v2\"\/><circle cx=\"9\" cy=\"7\" r=\"4\"\/><path d=\"M23 21v-2a4 4 0 0 0-3-3.87\"\/><path d=\"M16 3.13a4 4 0 0 1 0 7.75\"\/><\/svg>\n      <\/div>\n      <div>\n        <div class=\"cms-feat-title\">Die Verantwortung f\u00fcr Qualit\u00e4t verschiebt sich nicht von selbst<\/div>\n        <div class=\"cms-feat-body\">Wenn Qualit\u00e4t als Verantwortung des QA-Teams und nicht des Engineering-Teams betrachtet wird, wird KI-gest\u00fctztes Testen die Effizienz von QA steigern \u2013 es wird Qualit\u00e4t nicht zu einer gemeinsamen Angelegenheit machen. Das ist eine organisatorische \u00c4nderung, keine technische.<\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c27102 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c27102\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c854145\" data-id=\"c854145\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a58d022 elementor-widget elementor-widget-html\" data-id=\"a58d022\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2>Die Frage, die man sich zum KI-gest\u00fctzten Testen stellen sollte<\/h2>\n\n<p>Wenn wir mit Ingenieurteams \u00fcber Qualigentic sprechen, ist die Frage, die zu den n\u00fctzlichsten Gespr\u00e4chen f\u00fchrt, nicht: \"Wie viele weitere Tests werden wir generieren?\" Sie lautet: \"Was w\u00fcrden Sie mit der Zeit Ihres Teams anfangen, wenn die Testpflege nicht den gr\u00f6\u00dften Teil davon in Anspruch nehmen w\u00fcrde?\"<\/p>\n\n<p>Die Antworten sind vielf\u00e4ltig: mehr Zeit f\u00fcr exploratives Testen, mehr Investitionen in das Verst\u00e4ndnis daf\u00fcr, wie die Software tats\u00e4chlich genutzt wird, anstatt nur danach, wie sie spezifiziert wurde, und mehr Kapazit\u00e4t, sorgf\u00e4ltig \u00fcber die Ausfallmodi nachzudenken, die am wichtigsten sind, anstatt nur die abzudecken, die am einfachsten zu automatisieren sind. Hinzu kommt eine Teststrategie, die durch Dom\u00e4nenwissen gepr\u00e4gt ist und nicht durch die Grenzen der verf\u00fcgbaren technischen Bandbreite.<\/p>\n\n<p>Das sind die \u00c4nderungen, die sich im Laufe der Zeit anh\u00e4ufen \u2013 nicht der Deckungsgrad und auch nicht die Reduzierung gemeldeter Fehler pro Sprint. Letztendlich ist es die Neuzuweisung der Aufmerksamkeit von Experten auf die Arbeit, die Fachwissen erfordert, und weg von der Arbeit, die von einem System erledigt werden kann, das niemals m\u00fc.<\/p>\n\n<p>Das ist es, was sich wirklich \u00e4ndert, wenn ein Team KI-gest\u00fctztes Testen gut einsetzt. Das Werkzeug ist der Mechanismus, w\u00e4hrend sich die Ver\u00e4nderung darin zeigt, worauf sich das Team konzentrieren kann.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97553db elementor-widget elementor-widget-html\" data-id=\"97553db\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"display:flex; align-items:center; gap:16px; background:#f5f5f5; border-radius:8px; padding:16px 20px; margin-top:32px;\">\r\n  <img decoding=\"async\" src=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2023\/08\/CMS_Horizontal_Simple_Black.svg\" alt=\"Caixa M\u00e1gica Software\" style=\"width:180px; flex-shrink:0;\">\r\n  <div>\r\n    <div style=\"font-weight:700; font-size:15px; margin-bottom:4px;\">Caixa M\u00e1gica Team<\/div>\r\n    <div style=\"font-size:13px; color:#555;\">Caixa M\u00e1gica Software ist ein portugiesisches Softwareunternehmen mit \u00fcber 20 Jahren Erfahrung in der Bereitstellung von kundenspezifischer Software, KI-L\u00f6sungen und Nearshore-Entwicklungsteams f\u00fcr europ\u00e4ische Unternehmen.<\/div>\r\n  <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c4fff elementor-widget elementor-widget-html\" data-id=\"c1c4fff\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t  <div class=\"cms-cta-wrap\">\n    <div class=\"cms-cta-eyebrow\">Qualigentic \u00b7 Caixa M\u00e1gica Software<\/div>\n    <div class=\"cms-cta-title\">Sehen Sie, worauf sich Ihr Team konzentrieren k\u00f6nnte, wenn die Wartung nicht den gr\u00f6\u00dften Teil seiner Zeit in Anspruch nehmen w\u00fcrde<\/div>\n    <div class=\"cms-cta-sub\">KI-gest\u00fctzte Tests, entwickelt f\u00fcr Ingenieurteams, die Software liefern, bei der Qualit\u00e4t nicht optional ist.<\/div>\n    <div class=\"cms-cta-btns\">\n      <a href=\"https:\/\/caixamagica.pt\/de\/qualigentic\/\" class=\"cms-btn-secondary\">Erfahren Sie mehr \u00fcber Qualigentic<\/a>\n      <a href=\"https:\/\/caixamagica.pt\/de\/kontakt\/\" class=\"cms-btn-primary\">Sprechen Sie mit unserem Team<\/a>\n    <\/div>\n  <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1915c2 elementor-section-full_width related-case-studies elementor-section-height-default elementor-section-height-default\" data-id=\"b1915c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default container mb-5 pt-md-4 flex-wrap\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18b6fec col-12\" data-id=\"18b6fec\" data-element_type=\"column\">\n\t\t\t<div class=\"d-flex flex-sm-row flex-column align-items-center justify-content-between mb-4 pb-1 pb-md-3 p-0 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a6643c elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-highlighted-heading\" data-id=\"4a6643c\" data-element_type=\"widget\" data-widget_type=\"highlighted-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"silicon-elementor-highlighted-heading__title h2 mb-sm-0\"><span class=\"si-multipurpose-text__before\">Verwandte Erkenntnisse<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-148b008 elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-button\" data-id=\"148b008\" data-element_type=\"widget\" data-widget_type=\"button.button-silicon\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"\/de\/erfolgsgeschichten\/\" class=\"silicon-button btn btn-outline-primary btn-lg ms-4\" role=\"button\">\n\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text order-first\">Alle Beitr\u00e4ge anzeigen<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dd4ae30 col-12\" data-id=\"dd4ae30\" data-element_type=\"column\">\n\t\t\t<div class=\"p-0 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d8f17e elementor-widget elementor-widget-sn-post-carousel\" data-id=\"3d8f17e\" data-element_type=\"widget\" data-settings=\"{&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"sn-post-carousel.post-carousel-v1\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-swiper-options=\"{&quot;pagination&quot;:{&quot;el&quot;:&quot;.swiper-pagination&quot;,&quot;type&quot;:&quot;bullets&quot;,&quot;clickable&quot;:true},&quot;spaceBetween&quot;:8,&quot;breakpoints&quot;:{&quot;1440&quot;:{&quot;spaceBetween&quot;:8,&quot;slidesPerView&quot;:&quot;3&quot;},&quot;1000&quot;:{&quot;spaceBetween&quot;:24,&quot;slidesPerView&quot;:&quot;3&quot;},&quot;500&quot;:{&quot;spaceBetween&quot;:24,&quot;slidesPerView&quot;:&quot;2&quot;}},&quot;slidesPerView&quot;:1,&quot;speed&quot;:500}\" class=\"swiper sn-elementor-main-swiper mx-n2\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"swiper-slide h-auto pb-3\">\n\t\t\t\t\t<article class=\"card h-100 border-0 shadow-sm mx-2\">\n\t\t\t\t<div class=\"position-relative\">                     \n\t\t\t\t\t<a href=\"https:\/\/caixamagica.pt\/de\/insights\/ki-qualitatssicherung-qa-in-regulierten-branchen\/\" class=\"position-absolute top-0 start-0 w-100 h-100\" aria-label=\"Weiterlesen\"><\/a>\n\t\t\t\t\t<img decoding=\"async\" width=\"3200\" height=\"1800\" src=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries.png\" class=\"card-img-top rounded-top wp-post-image\" alt=\"\" srcset=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries.png 3200w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-300x169.png 300w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-1024x576.png 1024w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-768x432.png 768w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-1536x864.png 1536w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-2048x1152.png 2048w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/AI-QA-Testing-for-Regulated-Industries-18x10.png 18w\" sizes=\"(max-width: 3200px) 100vw, 3200px\" \/>         \n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"card-body pb-4\">\n\t\t\t\t\t\t<div class=\"d-flex align-items-center justify-content-between mb-3 sn-meta\">\n\t\t\t\t\t<div class=\"fs-sm\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<h3 class=\"silicon-elementor-title__name h5 mb-0 mb-1\">\n\t\t\t<a class=\"custom-title-color\" href=\"https:\/\/caixamagica.pt\/de\/insights\/ki-qualitatssicherung-qa-in-regulierten-branchen\/\">\n\t\t\t\tKI-Qualit\u00e4tssicherungstests f\u00fcr regulierte Branchen: Qualigentic vs. generische KI-Tools \n\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t<\/div>\n\t\t\t\t<div class=\"swiper-slide h-auto pb-3\">\n\t\t\t\t\t<article class=\"card h-100 border-0 shadow-sm mx-2\">\n\t\t\t\t<div class=\"position-relative\">                     \n\t\t\t\t\t<a href=\"https:\/\/caixamagica.pt\/de\/insights\/eidas-2-implementierungsleitfaden-2026\/\" class=\"position-absolute top-0 start-0 w-100 h-100\" aria-label=\"Weiterlesen\"><\/a>\n\t\t\t\t\t<img decoding=\"async\" width=\"3200\" height=\"1800\" src=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation.png\" class=\"card-img-top rounded-top wp-post-image\" alt=\"\" srcset=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation.png 3200w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-300x169.png 300w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-1024x576.png 1024w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-768x432.png 768w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-1536x864.png 1536w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-2048x1152.png 2048w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/eIDAS-2.0-Wallet-Implementation-18x10.png 18w\" sizes=\"(max-width: 3200px) 100vw, 3200px\" \/>         \n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"card-body pb-4 card-body pb-4\">\n\t\t\t\t\t\t<div class=\"d-flex align-items-center justify-content-between mb-3 sn-meta\">\n\t\t\t\t\t<div class=\"fs-sm\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<h3 class=\"silicon-elementor-title__name h5 mb-0 mb-1\">\n\t\t\t<a class=\"custom-title-color\" href=\"https:\/\/caixamagica.pt\/de\/insights\/eidas-2-implementierungsleitfaden-2026\/\">\n\t\t\t\teIDAS 2.0 Implementierungsleitfaden: Was Organisationen vor Dezember 2026 tun m\u00fcssen \n\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t<\/div>\n\t\t\t\t<div class=\"swiper-slide h-auto pb-3\">\n\t\t\t\t\t<article class=\"card h-100 border-0 shadow-sm mx-2\">\n\t\t\t\t<div class=\"position-relative\">                     \n\t\t\t\t\t<a href=\"https:\/\/caixamagica.pt\/de\/insights\/dora-belastbarkeitstest-qa-2026\/\" class=\"position-absolute top-0 start-0 w-100 h-100\" aria-label=\"Weiterlesen\"><\/a>\n\t\t\t\t\t<img decoding=\"async\" width=\"3200\" height=\"1800\" src=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026.png\" class=\"card-img-top rounded-top wp-post-image\" alt=\"\" srcset=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026.png 3200w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-300x169.png 300w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-1024x576.png 1024w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-768x432.png 768w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-1536x864.png 1536w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-2048x1152.png 2048w, https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/DORA-Resilience-Testing-in-2026-18x10.png 18w\" sizes=\"(max-width: 3200px) 100vw, 3200px\" \/>         \n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"card-body pb-4 card-body pb-4 card-body pb-4\">\n\t\t\t\t\t\t<div class=\"d-flex align-items-center justify-content-between mb-3 sn-meta\">\n\t\t\t\t\t<div class=\"fs-sm\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<h3 class=\"silicon-elementor-title__name h5 mb-0 mb-1\">\n\t\t\t<a class=\"custom-title-color\" href=\"https:\/\/caixamagica.pt\/de\/insights\/dora-belastbarkeitstest-qa-2026\/\">\n\t\t\t\tDORA Resilienz-Tests im Jahr 2026: Was QA-Teams bei Banken den Aufsichtsbeh\u00f6rden nachweisen m\u00fcssen \n\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/article>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-pagination position-relative pt-2 pt-sm-3 mt-4\"><\/div>        \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Aufbau von Qualigentic zwang uns, pr\u00e4zise zu sein, was sich tats\u00e4chlich ver\u00e4ndert, wenn KI in den Testablauf einflie\u00dft \u2013 nicht, was automatisiert wird, sondern was \u00fcberdacht wird. Das ist es, was wir hier teilen.<\/p>","protected":false},"featured_media":13793,"template":"elementor_theme","categorynews":[323],"etiqueta-news":[325,319,334,326],"class_list":["post-13798","new","type-new","status-publish","has-post-thumbnail","hentry","categorynews-articles","etiqueta-news-ai","etiqueta-news-llm","etiqueta-news-machine-learning","etiqueta-news-software"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AI-Assisted Testing: What Really Changes for Your Team | Insights<\/title>\n<meta name=\"description\" content=\"AI-assisted testing changes more than test volume \u2014 see what actually shifts in attention, coverage, timing and maintenance for QA teams.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caixamagica.pt\/de\/insights\/welche-anderungen-bringt-ki-gestutztes-testen-mit-sich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI-Assisted Testing: What Really Changes for Your Team | Insights\" \/>\n<meta property=\"og:description\" content=\"AI-assisted testing changes more than test volume \u2014 see what actually shifts in attention, coverage, timing and maintenance for QA teams.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caixamagica.pt\/de\/insights\/welche-anderungen-bringt-ki-gestutztes-testen-mit-sich\/\" \/>\n<meta property=\"og:site_name\" content=\"Caixa M\u00e1gica Software\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CaixaMagicaSoftware\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T09:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/07_07-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/\",\"url\":\"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/\",\"name\":\"AI-Assisted Testing: What Really Changes for Your Team | Insights\",\"isPartOf\":{\"@id\":\"https:\/\/caixamagica.pt\/#website\"},\"datePublished\":\"2026-07-07T07:39:05+00:00\",\"dateModified\":\"2026-07-14T09:38:56+00:00\",\"description\":\"AI-assisted testing changes more than test volume \u2014 see what actually shifts in attention, coverage, timing and maintenance for QA teams.\",\"breadcrumb\":{\"@id\":\"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/caixamagica.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What Really Changes When Your Team Starts Using AI-Assisted Testing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/caixamagica.pt\/#website\",\"url\":\"https:\/\/caixamagica.pt\/\",\"name\":\"Caixa M\u00e1gica Software\",\"description\":\"Caixa Magica Software create technological solutions in the areas of mobile, web, and automotive, with over 19 years of experience in developing for various market segments.\",\"publisher\":{\"@id\":\"https:\/\/caixamagica.pt\/#organization\"},\"alternateName\":\"CMS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/caixamagica.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/caixamagica.pt\/#organization\",\"name\":\"Caixa M\u00e1gica Software\",\"alternateName\":\"CMS\",\"url\":\"https:\/\/caixamagica.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/caixamagica.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2023\/09\/cropped-Favicon-CMS-v2.png\",\"contentUrl\":\"https:\/\/caixamagica.pt\/wp-content\/uploads\/2023\/09\/cropped-Favicon-CMS-v2.png\",\"width\":512,\"height\":512,\"caption\":\"Caixa M\u00e1gica Software\"},\"image\":{\"@id\":\"https:\/\/caixamagica.pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CaixaMagicaSoftware\",\"https:\/\/www.instagram.com\/caixamagicasoftware\/\",\"https:\/\/www.linkedin.com\/company\/caixa-magica-software\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KI-gest\u00fctzte Tests: Was sich f\u00fcr Ihr Team wirklich \u00e4ndert | Einblicke","description":"KI-gest\u00fctzte Tests \u00e4ndern mehr als nur das Testvolumen \u2013 sehen Sie, was sich tats\u00e4chlich in Bezug auf Aufmerksamkeit, Abdeckung, Zeitplanung und Wartung f\u00fcr QA-Teams verschiebt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caixamagica.pt\/de\/insights\/welche-anderungen-bringt-ki-gestutztes-testen-mit-sich\/","og_locale":"de_DE","og_type":"article","og_title":"AI-Assisted Testing: What Really Changes for Your Team | Insights","og_description":"AI-assisted testing changes more than test volume \u2014 see what actually shifts in attention, coverage, timing and maintenance for QA teams.","og_url":"https:\/\/caixamagica.pt\/de\/insights\/welche-anderungen-bringt-ki-gestutztes-testen-mit-sich\/","og_site_name":"Caixa M\u00e1gica Software","article_publisher":"https:\/\/www.facebook.com\/CaixaMagicaSoftware","article_modified_time":"2026-07-14T09:38:56+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/caixamagica.pt\/wp-content\/uploads\/2026\/07\/07_07-1024x576.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/","url":"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/","name":"KI-gest\u00fctzte Tests: Was sich f\u00fcr Ihr Team wirklich \u00e4ndert | Einblicke","isPartOf":{"@id":"https:\/\/caixamagica.pt\/#website"},"datePublished":"2026-07-07T07:39:05+00:00","dateModified":"2026-07-14T09:38:56+00:00","description":"KI-gest\u00fctzte Tests \u00e4ndern mehr als nur das Testvolumen \u2013 sehen Sie, was sich tats\u00e4chlich in Bezug auf Aufmerksamkeit, Abdeckung, Zeitplanung und Wartung f\u00fcr QA-Teams verschiebt.","breadcrumb":{"@id":"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/caixamagica.pt\/insights\/what-changes-ai-assisted-testing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/caixamagica.pt\/"},{"@type":"ListItem","position":2,"name":"What Really Changes When Your Team Starts Using AI-Assisted Testing"}]},{"@type":"WebSite","@id":"https:\/\/caixamagica.pt\/#website","url":"https:\/\/caixamagica.pt\/","name":"Caixa M\u00e1gica Software","description":"Caixa Magica Software entwickelt technologische L\u00f6sungen in den Bereichen Mobile, Web und Automotive mit \u00fcber 19 Jahren Erfahrung in der Entwicklung f\u00fcr verschiedene Marktsegmente.","publisher":{"@id":"https:\/\/caixamagica.pt\/#organization"},"alternateName":"CMS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caixamagica.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/caixamagica.pt\/#organization","name":"Caixa M\u00e1gica Software","alternateName":"CMS","url":"https:\/\/caixamagica.pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/caixamagica.pt\/#\/schema\/logo\/image\/","url":"https:\/\/caixamagica.pt\/wp-content\/uploads\/2023\/09\/cropped-Favicon-CMS-v2.png","contentUrl":"https:\/\/caixamagica.pt\/wp-content\/uploads\/2023\/09\/cropped-Favicon-CMS-v2.png","width":512,"height":512,"caption":"Caixa M\u00e1gica Software"},"image":{"@id":"https:\/\/caixamagica.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CaixaMagicaSoftware","https:\/\/www.instagram.com\/caixamagicasoftware\/","https:\/\/www.linkedin.com\/company\/caixa-magica-software"]}]}},"_links":{"self":[{"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/new\/13798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":16,"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/new\/13798\/revisions"}],"predecessor-version":[{"id":14086,"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/new\/13798\/revisions\/14086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/media\/13793"}],"wp:attachment":[{"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/media?parent=13798"}],"wp:term":[{"taxonomy":"categorynews","embeddable":true,"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/categorynews?post=13798"},{"taxonomy":"etiqueta-news","embeddable":true,"href":"https:\/\/caixamagica.pt\/de\/wp-json\/wp\/v2\/etiqueta-news?post=13798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}